{"id":1034,"date":"2023-05-16T13:16:05","date_gmt":"2023-05-16T13:16:05","guid":{"rendered":"https:\/\/zenboat.local\/?post_type=itineraries&#038;p=1034"},"modified":"2023-07-05T16:18:14","modified_gmt":"2023-07-05T16:18:14","slug":"ionian-odyssey","status":"publish","type":"itineraries","link":"https:\/\/zen-boat.com\/fr\/itinerary\/ionian-odyssey\/","title":{"rendered":"Ionian Odyssey"},"excerpt":{"rendered":"","protected":false},"featured_media":0,"comment_status":"open","ping_status":"closed","template":"","itinerary_types":[],"travel_locations":[],"travel_keywords":[],"activity":[],"class_list":["post-1034","itineraries","type-itineraries","status-publish","hentry"],"acf":[],"yoast_head":"<!-- This site is optimized with the Yoast SEO plugin v27.6 - https:\/\/yoast.com\/product\/yoast-seo-wordpress\/ -->\n<title>Ionian Odyssey - ZenBoat<\/title>\n<meta name=\"robots\" content=\"index, follow, max-snippet:-1, max-image-preview:large, max-video-preview:-1\" \/>\n<link rel=\"canonical\" href=\"https:\/\/zen-boat.com\/fr\/itinerary\/ionian-odyssey\/\" \/>\n<meta property=\"og:locale\" content=\"fr_FR\" \/>\n<meta property=\"og:type\" content=\"article\" \/>\n<meta property=\"og:title\" content=\"Ionian Odyssey - ZenBoat\" \/>\n<meta property=\"og:url\" content=\"https:\/\/zen-boat.com\/fr\/itinerary\/ionian-odyssey\/\" \/>\n<meta property=\"og:site_name\" content=\"ZenBoat\" \/>\n<meta property=\"article:modified_time\" content=\"2023-07-05T16:18:14+00:00\" \/>\n<meta name=\"twitter:card\" content=\"summary_large_image\" \/>\n<script type=\"application\/ld+json\" class=\"yoast-schema-graph\">{\"@context\":\"https:\\\/\\\/schema.org\",\"@graph\":[{\"@type\":\"WebPage\",\"@id\":\"https:\\\/\\\/zen-boat.com\\\/itinerary\\\/ionian-odyssey\\\/\",\"url\":\"https:\\\/\\\/zen-boat.com\\\/itinerary\\\/ionian-odyssey\\\/\",\"name\":\"Ionian Odyssey - ZenBoat\",\"isPartOf\":{\"@id\":\"https:\\\/\\\/zen-boat.com\\\/#website\"},\"datePublished\":\"2023-05-16T13:16:05+00:00\",\"dateModified\":\"2023-07-05T16:18:14+00:00\",\"breadcrumb\":{\"@id\":\"https:\\\/\\\/zen-boat.com\\\/itinerary\\\/ionian-odyssey\\\/#breadcrumb\"},\"inLanguage\":\"fr-FR\",\"potentialAction\":[{\"@type\":\"ReadAction\",\"target\":[\"https:\\\/\\\/zen-boat.com\\\/itinerary\\\/ionian-odyssey\\\/\"]}]},{\"@type\":\"BreadcrumbList\",\"@id\":\"https:\\\/\\\/zen-boat.com\\\/itinerary\\\/ionian-odyssey\\\/#breadcrumb\",\"itemListElement\":[{\"@type\":\"ListItem\",\"position\":1,\"name\":\"Home\",\"item\":\"https:\\\/\\\/zen-boat.com\\\/\"},{\"@type\":\"ListItem\",\"position\":2,\"name\":\"Trips\",\"item\":\"https:\\\/\\\/zen-boat.com\\\/itinerary\\\/\"},{\"@type\":\"ListItem\",\"position\":3,\"name\":\"Ionian Odyssey\"}]},{\"@type\":\"WebSite\",\"@id\":\"https:\\\/\\\/zen-boat.com\\\/#website\",\"url\":\"https:\\\/\\\/zen-boat.com\\\/\",\"name\":\"ZenBoat\",\"description\":\"Luxury Sailing Trips\",\"publisher\":{\"@id\":\"https:\\\/\\\/zen-boat.com\\\/#organization\"},\"potentialAction\":[{\"@type\":\"SearchAction\",\"target\":{\"@type\":\"EntryPoint\",\"urlTemplate\":\"https:\\\/\\\/zen-boat.com\\\/?s={search_term_string}\"},\"query-input\":{\"@type\":\"PropertyValueSpecification\",\"valueRequired\":true,\"valueName\":\"search_term_string\"}}],\"inLanguage\":\"fr-FR\"},{\"@type\":\"Organization\",\"@id\":\"https:\\\/\\\/zen-boat.com\\\/#organization\",\"name\":\"ZenBoat\",\"url\":\"https:\\\/\\\/zen-boat.com\\\/\",\"logo\":{\"@type\":\"ImageObject\",\"inLanguage\":\"fr-FR\",\"@id\":\"https:\\\/\\\/zen-boat.com\\\/#\\\/schema\\\/logo\\\/image\\\/\",\"url\":\"https:\\\/\\\/zen-boat.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo.svg\",\"contentUrl\":\"https:\\\/\\\/zen-boat.com\\\/wp-content\\\/uploads\\\/2022\\\/12\\\/logo.svg\",\"width\":\"1024\",\"height\":\"1024\",\"caption\":\"ZenBoat\"},\"image\":{\"@id\":\"https:\\\/\\\/zen-boat.com\\\/#\\\/schema\\\/logo\\\/image\\\/\"}}]}<\/script>\n<!-- \/ Yoast SEO plugin. -->","yoast_head_json":{"title":"Ionian Odyssey - ZenBoat","robots":{"index":"index","follow":"follow","max-snippet":"max-snippet:-1","max-image-preview":"max-image-preview:large","max-video-preview":"max-video-preview:-1"},"canonical":"https:\/\/zen-boat.com\/fr\/itinerary\/ionian-odyssey\/","og_locale":"fr_FR","og_type":"article","og_title":"Ionian Odyssey - ZenBoat","og_url":"https:\/\/zen-boat.com\/fr\/itinerary\/ionian-odyssey\/","og_site_name":"ZenBoat","article_modified_time":"2023-07-05T16:18:14+00:00","twitter_card":"summary_large_image","schema":{"@context":"https:\/\/schema.org","@graph":[{"@type":"WebPage","@id":"https:\/\/zen-boat.com\/itinerary\/ionian-odyssey\/","url":"https:\/\/zen-boat.com\/itinerary\/ionian-odyssey\/","name":"Ionian Odyssey - ZenBoat","isPartOf":{"@id":"https:\/\/zen-boat.com\/#website"},"datePublished":"2023-05-16T13:16:05+00:00","dateModified":"2023-07-05T16:18:14+00:00","breadcrumb":{"@id":"https:\/\/zen-boat.com\/itinerary\/ionian-odyssey\/#breadcrumb"},"inLanguage":"fr-FR","potentialAction":[{"@type":"ReadAction","target":["https:\/\/zen-boat.com\/itinerary\/ionian-odyssey\/"]}]},{"@type":"BreadcrumbList","@id":"https:\/\/zen-boat.com\/itinerary\/ionian-odyssey\/#breadcrumb","itemListElement":[{"@type":"ListItem","position":1,"name":"Home","item":"https:\/\/zen-boat.com\/"},{"@type":"ListItem","position":2,"name":"Trips","item":"https:\/\/zen-boat.com\/itinerary\/"},{"@type":"ListItem","position":3,"name":"Ionian Odyssey"}]},{"@type":"WebSite","@id":"https:\/\/zen-boat.com\/#website","url":"https:\/\/zen-boat.com\/","name":"ZenBoat","description":"Luxury Sailing Trips","publisher":{"@id":"https:\/\/zen-boat.com\/#organization"},"potentialAction":[{"@type":"SearchAction","target":{"@type":"EntryPoint","urlTemplate":"https:\/\/zen-boat.com\/?s={search_term_string}"},"query-input":{"@type":"PropertyValueSpecification","valueRequired":true,"valueName":"search_term_string"}}],"inLanguage":"fr-FR"},{"@type":"Organization","@id":"https:\/\/zen-boat.com\/#organization","name":"ZenBoat","url":"https:\/\/zen-boat.com\/","logo":{"@type":"ImageObject","inLanguage":"fr-FR","@id":"https:\/\/zen-boat.com\/#\/schema\/logo\/image\/","url":"https:\/\/zen-boat.com\/wp-content\/uploads\/2022\/12\/logo.svg","contentUrl":"https:\/\/zen-boat.com\/wp-content\/uploads\/2022\/12\/logo.svg","width":"1024","height":"1024","caption":"ZenBoat"},"image":{"@id":"https:\/\/zen-boat.com\/#\/schema\/logo\/image\/"}}]}},"_links":{"self":[{"href":"https:\/\/zen-boat.com\/fr\/wp-json\/wp\/v2\/itineraries\/1034","targetHints":{"allow":["GET"]}}],"collection":[{"href":"https:\/\/zen-boat.com\/fr\/wp-json\/wp\/v2\/itineraries"}],"about":[{"href":"https:\/\/zen-boat.com\/fr\/wp-json\/wp\/v2\/types\/itineraries"}],"replies":[{"embeddable":true,"href":"https:\/\/zen-boat.com\/fr\/wp-json\/wp\/v2\/comments?post=1034"}],"version-history":[{"count":11,"href":"https:\/\/zen-boat.com\/fr\/wp-json\/wp\/v2\/itineraries\/1034\/revisions"}],"predecessor-version":[{"id":1131,"href":"https:\/\/zen-boat.com\/fr\/wp-json\/wp\/v2\/itineraries\/1034\/revisions\/1131"}],"wp:attachment":[{"href":"https:\/\/zen-boat.com\/fr\/wp-json\/wp\/v2\/media?parent=1034"}],"wp:term":[{"taxonomy":"itinerary_types","embeddable":true,"href":"https:\/\/zen-boat.com\/fr\/wp-json\/wp\/v2\/itinerary_types?post=1034"},{"taxonomy":"travel_locations","embeddable":true,"href":"https:\/\/zen-boat.com\/fr\/wp-json\/wp\/v2\/travel_locations?post=1034"},{"taxonomy":"travel_keywords","embeddable":true,"href":"https:\/\/zen-boat.com\/fr\/wp-json\/wp\/v2\/travel_keywords?post=1034"},{"taxonomy":"activity","embeddable":true,"href":"https:\/\/zen-boat.com\/fr\/wp-json\/wp\/v2\/activity?post=1034"}],"curies":[{"name":"wp","href":"https:\/\/api.w.org\/{rel}","templated":true}]}}